{"id":106418,"date":"2025-12-25T05:49:20","date_gmt":"2025-12-25T05:49:20","guid":{"rendered":"https:\/\/advbiomart.sytech.site\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/"},"modified":"2026-03-28T23:05:41","modified_gmt":"2026-03-28T23:05:41","slug":"human-phospho-bad-s112-monoclonal-antibody-ada-16161a","status":"publish","type":"product","link":"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/","title":{"rendered":"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The antibody against Phospho-Bad-S112 was raised in Rabbit using a synthetic phosphorylated peptide around S112 of human BAD (Q92934) as the immunogen. The monoclonal antibody exists as a isotype IgG, by affinity purification. This antibody has been validated on WB, ELISA.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,86],"product_tag":[49866],"class_list":["post-106418","product","type-product","status-publish","product_cat-antibodies","product_cat-phospho-specific-antibodies","product_tag-bad","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody - AbTrivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/\" \/>\n<meta property=\"og:locale\" content=\"cn_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody - AbTrivia\" \/>\n<meta property=\"og:description\" content=\"The antibody against Phospho-Bad-S112 was raised in Rabbit using a synthetic phosphorylated peptide around S112 of human BAD (Q92934) as the immunogen. The monoclonal antibody exists as a isotype IgG, by affinity purification. This antibody has been validated on WB, ELISA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/\" \/>\n<meta property=\"og:site_name\" content=\"AbTrivia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T23:05:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/\",\"url\":\"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/\",\"name\":\"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody - AbTrivia\",\"isPartOf\":{\"@id\":\"https:\/\/abtriva.com\/cn\/#website\"},\"datePublished\":\"2025-12-25T05:49:20+00:00\",\"dateModified\":\"2026-03-28T23:05:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/#breadcrumb\"},\"inLanguage\":\"cn_CN\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abtriva.com\/cn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.abtriva.com\/cn\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antibodies\",\"item\":\"https:\/\/www.abtriva.com\/cn\/category\/antibodies\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Phospho-specific Antibodies\",\"item\":\"https:\/\/www.abtriva.com\/cn\/category\/antibodies\/phospho-specific-antibodies\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abtriva.com\/cn\/#website\",\"url\":\"https:\/\/abtriva.com\/cn\/\",\"name\":\"AbTrivia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abtriva.com\/cn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"cn_CN\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody - AbTrivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/","og_locale":"cn_CN","og_type":"article","og_title":"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody - AbTrivia","og_description":"The antibody against Phospho-Bad-S112 was raised in Rabbit using a synthetic phosphorylated peptide around S112 of human BAD (Q92934) as the immunogen. The monoclonal antibody exists as a isotype IgG, by affinity purification. This antibody has been validated on WB, ELISA.","og_url":"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/","og_site_name":"AbTrivia","article_modified_time":"2026-03-28T23:05:41+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/","url":"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/","name":"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody - AbTrivia","isPartOf":{"@id":"https:\/\/abtriva.com\/cn\/#website"},"datePublished":"2025-12-25T05:49:20+00:00","dateModified":"2026-03-28T23:05:41+00:00","breadcrumb":{"@id":"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/#breadcrumb"},"inLanguage":"cn_CN","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.abtriva.com\/cn\/product\/human-phospho-bad-s112-monoclonal-antibody-ada-16161a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abtriva.com\/cn\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.abtriva.com\/cn\/shop\/"},{"@type":"ListItem","position":3,"name":"Antibodies","item":"https:\/\/www.abtriva.com\/cn\/category\/antibodies\/"},{"@type":"ListItem","position":4,"name":"Phospho-specific Antibodies","item":"https:\/\/www.abtriva.com\/cn\/category\/antibodies\/phospho-specific-antibodies\/"},{"@type":"ListItem","position":5,"name":"Rabbit anti-Human Phospho-Bad-S112 Monoclonal Antibody"}]},{"@type":"WebSite","@id":"https:\/\/abtriva.com\/cn\/#website","url":"https:\/\/abtriva.com\/cn\/","name":"AbTrivia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abtriva.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"cn_CN"}]}},"_links":{"self":[{"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/product\/106418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/comments?post=106418"}],"wp:attachment":[{"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/media?parent=106418"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/product_brand?post=106418"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/product_cat?post=106418"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.abtriva.com\/cn\/wp-json\/wp\/v2\/product_tag?post=106418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}