{"id":103889,"date":"2025-12-24T13:50:57","date_gmt":"2025-12-24T13:50:57","guid":{"rendered":"https:\/\/advbiomart.sytech.site\/product\/human-numa1-monoclonal-antibody-ada-13861a\/"},"modified":"2026-03-28T22:09:39","modified_gmt":"2026-03-28T22:09:39","slug":"human-numa1-monoclonal-antibody-ada-13861a","status":"publish","type":"product","link":"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/","title":{"rendered":"Rabbit anti-Human NUMA1 Monoclonal Antibody"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The antibody against NUMA1 was raised in Rabbit using a synthetic peptide corresponding to a sequence within amino acids 2000-2100 of human NUMA11 (Q14980) as the immunogen. The monoclonal antibody exists as a isotype IgG, by affinity purification. This antibody has been validated on WB, IHC-P, ELISA.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,107],"product_tag":[12533],"class_list":["post-103889","product","type-product","status-publish","product_cat-antibodies","product_cat-monoclonal-antibodies","product_tag-numa1","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rabbit anti-Human NUMA1 Monoclonal Antibody - AbTrivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rabbit anti-Human NUMA1 Monoclonal Antibody - AbTrivia\" \/>\n<meta property=\"og:description\" content=\"The antibody against NUMA1 was raised in Rabbit using a synthetic peptide corresponding to a sequence within amino acids 2000-2100 of human NUMA11 (Q14980) as the immunogen. The monoclonal antibody exists as a isotype IgG, by affinity purification. This antibody has been validated on WB, IHC-P, ELISA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/\" \/>\n<meta property=\"og:site_name\" content=\"AbTrivia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T22:09:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/\",\"url\":\"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/\",\"name\":\"Rabbit anti-Human NUMA1 Monoclonal Antibody - AbTrivia\",\"isPartOf\":{\"@id\":\"https:\/\/abtriva.com\/cn\/#website\"},\"datePublished\":\"2025-12-24T13:50:57+00:00\",\"dateModified\":\"2026-03-28T22:09:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/#breadcrumb\"},\"inLanguage\":\"ko_KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abtriva.com\/ko\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.abtriva.com\/ko\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antibodies\",\"item\":\"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Monoclonal Antibodies\",\"item\":\"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/monoclonal-antibodies\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Rabbit anti-Human NUMA1 Monoclonal Antibody\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abtriva.com\/cn\/#website\",\"url\":\"https:\/\/abtriva.com\/cn\/\",\"name\":\"AbTrivia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abtriva.com\/cn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko_KR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rabbit anti-Human NUMA1 Monoclonal Antibody - AbTrivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/","og_locale":"ko_KR","og_type":"article","og_title":"Rabbit anti-Human NUMA1 Monoclonal Antibody - AbTrivia","og_description":"The antibody against NUMA1 was raised in Rabbit using a synthetic peptide corresponding to a sequence within amino acids 2000-2100 of human NUMA11 (Q14980) as the immunogen. The monoclonal antibody exists as a isotype IgG, by affinity purification. This antibody has been validated on WB, IHC-P, ELISA.","og_url":"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/","og_site_name":"AbTrivia","article_modified_time":"2026-03-28T22:09:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/","url":"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/","name":"Rabbit anti-Human NUMA1 Monoclonal Antibody - AbTrivia","isPartOf":{"@id":"https:\/\/abtriva.com\/cn\/#website"},"datePublished":"2025-12-24T13:50:57+00:00","dateModified":"2026-03-28T22:09:39+00:00","breadcrumb":{"@id":"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/#breadcrumb"},"inLanguage":"ko_KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.abtriva.com\/ko\/product\/human-numa1-monoclonal-antibody-ada-13861a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abtriva.com\/ko\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.abtriva.com\/ko\/shop\/"},{"@type":"ListItem","position":3,"name":"Antibodies","item":"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/"},{"@type":"ListItem","position":4,"name":"Monoclonal Antibodies","item":"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/monoclonal-antibodies\/"},{"@type":"ListItem","position":5,"name":"Rabbit anti-Human NUMA1 Monoclonal Antibody"}]},{"@type":"WebSite","@id":"https:\/\/abtriva.com\/cn\/#website","url":"https:\/\/abtriva.com\/cn\/","name":"AbTrivia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abtriva.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko_KR"}]}},"_links":{"self":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product\/103889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/comments?post=103889"}],"wp:attachment":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/media?parent=103889"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_brand?post=103889"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_cat?post=103889"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_tag?post=103889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}