{"id":111671,"date":"2025-12-25T14:51:11","date_gmt":"2025-12-25T14:51:11","guid":{"rendered":"https:\/\/advbiomart.sytech.site\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/"},"modified":"2025-12-25T14:51:12","modified_gmt":"2025-12-25T14:51:12","slug":"recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379","status":"publish","type":"product","link":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/","title":{"rendered":"Recombinant Human Adenylate kinase isoenzyme 1 (AK1)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[168834,18],"product_tag":[25067],"class_list":["post-111671","product","type-product","status-publish","product_cat-proteins","product_cat-recombinant-proteins","product_tag-ak1","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recombinant Human Adenylate kinase isoenzyme 1 (AK1) - AbTrivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recombinant Human Adenylate kinase isoenzyme 1 (AK1) - AbTrivia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/\" \/>\n<meta property=\"og:site_name\" content=\"AbTrivia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-25T14:51:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/\",\"url\":\"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/\",\"name\":\"Recombinant Human Adenylate kinase isoenzyme 1 (AK1) - AbTrivia\",\"isPartOf\":{\"@id\":\"https:\/\/abtriva.com\/cn\/#website\"},\"datePublished\":\"2025-12-25T14:51:11+00:00\",\"dateModified\":\"2025-12-25T14:51:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/#breadcrumb\"},\"inLanguage\":\"ko_KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abtriva.com\/ko\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.abtriva.com\/ko\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Recombinant Human Adenylate kinase isoenzyme 1 (AK1)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abtriva.com\/cn\/#website\",\"url\":\"https:\/\/abtriva.com\/cn\/\",\"name\":\"AbTrivia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abtriva.com\/cn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko_KR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recombinant Human Adenylate kinase isoenzyme 1 (AK1) - AbTrivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/","og_locale":"ko_KR","og_type":"article","og_title":"Recombinant Human Adenylate kinase isoenzyme 1 (AK1) - AbTrivia","og_url":"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/","og_site_name":"AbTrivia","article_modified_time":"2025-12-25T14:51:12+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/","url":"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/","name":"Recombinant Human Adenylate kinase isoenzyme 1 (AK1) - AbTrivia","isPartOf":{"@id":"https:\/\/abtriva.com\/cn\/#website"},"datePublished":"2025-12-25T14:51:11+00:00","dateModified":"2025-12-25T14:51:12+00:00","breadcrumb":{"@id":"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/#breadcrumb"},"inLanguage":"ko_KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.abtriva.com\/ko\/de\/product\/recombinant-human-adenylate-kinase-isoenzyme-1-ak1-acp04379\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abtriva.com\/ko\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.abtriva.com\/ko\/shop\/"},{"@type":"ListItem","position":3,"name":"Recombinant Human Adenylate kinase isoenzyme 1 (AK1)"}]},{"@type":"WebSite","@id":"https:\/\/abtriva.com\/cn\/#website","url":"https:\/\/abtriva.com\/cn\/","name":"AbTrivia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abtriva.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko_KR"}]}},"_links":{"self":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product\/111671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/comments?post=111671"}],"wp:attachment":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/media?parent=111671"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_brand?post=111671"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_cat?post=111671"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_tag?post=111671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}