{"id":123784,"date":"2025-12-25T22:29:49","date_gmt":"2025-12-25T22:29:49","guid":{"rendered":"https:\/\/advbiomart.sytech.site\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/"},"modified":"2025-12-25T22:29:50","modified_gmt":"2025-12-25T22:29:50","slug":"recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530","status":"publish","type":"product","link":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/","title":{"rendered":"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[168834,18],"product_tag":[73982],"class_list":["post-123784","product","type-product","status-publish","product_cat-proteins","product_cat-recombinant-proteins","product_tag-ldhal6a","first","instock","shipping-taxable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A) - AbTrivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A) - AbTrivia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/\" \/>\n<meta property=\"og:site_name\" content=\"AbTrivia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-25T22:29:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/\",\"url\":\"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/\",\"name\":\"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A) - AbTrivia\",\"isPartOf\":{\"@id\":\"https:\/\/abtriva.com\/cn\/#website\"},\"datePublished\":\"2025-12-25T22:29:49+00:00\",\"dateModified\":\"2025-12-25T22:29:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/#breadcrumb\"},\"inLanguage\":\"ko_KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abtriva.com\/ko\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.abtriva.com\/ko\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Proteins\",\"item\":\"https:\/\/www.abtriva.com\/ko\/category\/proteins\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Recombinant Proteins\",\"item\":\"https:\/\/www.abtriva.com\/ko\/category\/proteins\/recombinant-proteins\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abtriva.com\/cn\/#website\",\"url\":\"https:\/\/abtriva.com\/cn\/\",\"name\":\"AbTrivia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abtriva.com\/cn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko_KR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A) - AbTrivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/","og_locale":"ko_KR","og_type":"article","og_title":"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A) - AbTrivia","og_url":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/","og_site_name":"AbTrivia","article_modified_time":"2025-12-25T22:29:50+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/","url":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/","name":"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A) - AbTrivia","isPartOf":{"@id":"https:\/\/abtriva.com\/cn\/#website"},"datePublished":"2025-12-25T22:29:49+00:00","dateModified":"2025-12-25T22:29:50+00:00","breadcrumb":{"@id":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/#breadcrumb"},"inLanguage":"ko_KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.abtriva.com\/ko\/product\/recombinant-human-l-lactate-dehydrogenase-a-like-6a-ldhal6a-acp16530\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abtriva.com\/ko\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.abtriva.com\/ko\/shop\/"},{"@type":"ListItem","position":3,"name":"Proteins","item":"https:\/\/www.abtriva.com\/ko\/category\/proteins\/"},{"@type":"ListItem","position":4,"name":"Recombinant Proteins","item":"https:\/\/www.abtriva.com\/ko\/category\/proteins\/recombinant-proteins\/"},{"@type":"ListItem","position":5,"name":"Recombinant Human L-lactate dehydrogenase A-like 6A (LDHAL6A)"}]},{"@type":"WebSite","@id":"https:\/\/abtriva.com\/cn\/#website","url":"https:\/\/abtriva.com\/cn\/","name":"AbTrivia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abtriva.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko_KR"}]}},"_links":{"self":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product\/123784","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/comments?post=123784"}],"wp:attachment":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/media?parent=123784"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_brand?post=123784"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_cat?post=123784"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_tag?post=123784"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}