{"id":87162,"date":"2025-12-23T02:26:37","date_gmt":"2025-12-23T02:26:37","guid":{"rendered":"https:\/\/advbiomart.sytech.site\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/"},"modified":"2026-03-28T12:09:36","modified_gmt":"2026-03-28T12:09:36","slug":"nup98-recombinant-monoclonal-antibody-adc-56846a","status":"publish","type":"product","link":"https:\/\/www.abtriva.com\/ko\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/","title":{"rendered":"NUP98 Recombinant Monoclonal Antibody"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The recombinant antibody against NUP98 was produced using a synthesized peptide derived from human NUP98 as the immunogen. This antibody exists as a non-conjugated isotype Rabbit IgG, Affinity-chromatography purified. This antibody has been validated on ELISA, WB, IHC, IF.<\/p>\n","protected":false},"featured_media":100833,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,83],"product_tag":[9947],"class_list":["post-87162","product","type-product","status-publish","has-post-thumbnail","product_cat-antibodies","product_cat-recombinant-antibodies","product_tag-nup98","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUP98 Recombinant Monoclonal Antibody - AbTrivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUP98 Recombinant Monoclonal Antibody - AbTrivia\" \/>\n<meta property=\"og:description\" content=\"The recombinant antibody against NUP98 was produced using a synthesized peptide derived from human NUP98 as the immunogen. This antibody exists as a non-conjugated isotype Rabbit IgG, Affinity-chromatography purified. This antibody has been validated on ELISA, WB, IHC, IF.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/\" \/>\n<meta property=\"og:site_name\" content=\"AbTrivia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T12:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.abtriva.com\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"141\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/\",\"url\":\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/\",\"name\":\"NUP98 Recombinant Monoclonal Antibody - AbTrivia\",\"isPartOf\":{\"@id\":\"https:\/\/abtriva.com\/cn\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.abtriva.com\/ko\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg\",\"datePublished\":\"2025-12-23T02:26:37+00:00\",\"dateModified\":\"2026-03-28T12:09:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#breadcrumb\"},\"inLanguage\":\"ko_KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ko_KR\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#primaryimage\",\"url\":\"https:\/\/www.abtriva.com\/ko\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg\",\"contentUrl\":\"https:\/\/www.abtriva.com\/ko\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg\",\"width\":141,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abtriva.com\/ko\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.abtriva.com\/ko\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"NUP98 Recombinant Monoclonal Antibody\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abtriva.com\/cn\/#website\",\"url\":\"https:\/\/abtriva.com\/cn\/\",\"name\":\"AbTrivia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abtriva.com\/cn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko_KR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUP98 Recombinant Monoclonal Antibody - AbTrivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/","og_locale":"ko_KR","og_type":"article","og_title":"NUP98 Recombinant Monoclonal Antibody - AbTrivia","og_description":"The recombinant antibody against NUP98 was produced using a synthesized peptide derived from human NUP98 as the immunogen. This antibody exists as a non-conjugated isotype Rabbit IgG, Affinity-chromatography purified. This antibody has been validated on ELISA, WB, IHC, IF.","og_url":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/","og_site_name":"AbTrivia","article_modified_time":"2026-03-28T12:09:36+00:00","og_image":[{"width":141,"height":250,"url":"https:\/\/www.abtriva.com\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/","url":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/","name":"NUP98 Recombinant Monoclonal Antibody - AbTrivia","isPartOf":{"@id":"https:\/\/abtriva.com\/cn\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#primaryimage"},"image":{"@id":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#primaryimage"},"thumbnailUrl":"https:\/\/www.abtriva.com\/ko\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg","datePublished":"2025-12-23T02:26:37+00:00","dateModified":"2026-03-28T12:09:36+00:00","breadcrumb":{"@id":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#breadcrumb"},"inLanguage":"ko_KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/"]}]},{"@type":"ImageObject","inLanguage":"ko_KR","@id":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#primaryimage","url":"https:\/\/www.abtriva.com\/ko\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg","contentUrl":"https:\/\/www.abtriva.com\/ko\/wp-content\/uploads\/2025\/12\/CSB-RA995655A0HU-WB-2.jpg","width":141,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/www.abtriva.com\/ko\/es\/product\/nup98-recombinant-monoclonal-antibody-adc-56846a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abtriva.com\/ko\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.abtriva.com\/ko\/shop\/"},{"@type":"ListItem","position":3,"name":"NUP98 Recombinant Monoclonal Antibody"}]},{"@type":"WebSite","@id":"https:\/\/abtriva.com\/cn\/#website","url":"https:\/\/abtriva.com\/cn\/","name":"AbTrivia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abtriva.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko_KR"}]}},"_links":{"self":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product\/87162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/comments?post=87162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/media\/100833"}],"wp:attachment":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/media?parent=87162"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_brand?post=87162"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_cat?post=87162"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_tag?post=87162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}