{"id":88082,"date":"2025-12-23T03:59:21","date_gmt":"2025-12-23T03:59:21","guid":{"rendered":"https:\/\/advbiomart.sytech.site\/product\/neomycin-monoclonal-antibody-adc-57244a\/"},"modified":"2026-03-28T12:34:08","modified_gmt":"2026-03-28T12:34:08","slug":"neomycin-monoclonal-antibody-adc-57244a","status":"publish","type":"product","link":"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/","title":{"rendered":"Neomycin Monoclonal Antibody"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>The Antibody against NMC was raised in Mouse. This antibody exists as a non-conjugated monoclonal antibody, purified by protein G with a purity greater than 95%.<\/p>\n","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[17,88],"product_tag":[88791],"class_list":["post-88082","product","type-product","status-publish","product_cat-antibodies","product_cat-small-molecules-antibodies","product_tag-nmc","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neomycin Monoclonal Antibody - AbTrivia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neomycin Monoclonal Antibody - AbTrivia\" \/>\n<meta property=\"og:description\" content=\"The Antibody against NMC was raised in Mouse. This antibody exists as a non-conjugated monoclonal antibody, purified by protein G with a purity greater than 95%.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/\" \/>\n<meta property=\"og:site_name\" content=\"AbTrivia\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-28T12:34:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/\",\"url\":\"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/\",\"name\":\"Neomycin Monoclonal Antibody - AbTrivia\",\"isPartOf\":{\"@id\":\"https:\/\/abtriva.com\/cn\/#website\"},\"datePublished\":\"2025-12-23T03:59:21+00:00\",\"dateModified\":\"2026-03-28T12:34:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/#breadcrumb\"},\"inLanguage\":\"ko_KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.abtriva.com\/ko\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/www.abtriva.com\/ko\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Antibodies\",\"item\":\"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Small Molecules Antibodies\",\"item\":\"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/small-molecules-antibodies\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Neomycin Monoclonal Antibody\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/abtriva.com\/cn\/#website\",\"url\":\"https:\/\/abtriva.com\/cn\/\",\"name\":\"AbTrivia\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/abtriva.com\/cn\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ko_KR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neomycin Monoclonal Antibody - AbTrivia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/","og_locale":"ko_KR","og_type":"article","og_title":"Neomycin Monoclonal Antibody - AbTrivia","og_description":"The Antibody against NMC was raised in Mouse. This antibody exists as a non-conjugated monoclonal antibody, purified by protein G with a purity greater than 95%.","og_url":"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/","og_site_name":"AbTrivia","article_modified_time":"2026-03-28T12:34:08+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/","url":"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/","name":"Neomycin Monoclonal Antibody - AbTrivia","isPartOf":{"@id":"https:\/\/abtriva.com\/cn\/#website"},"datePublished":"2025-12-23T03:59:21+00:00","dateModified":"2026-03-28T12:34:08+00:00","breadcrumb":{"@id":"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/#breadcrumb"},"inLanguage":"ko_KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.abtriva.com\/ko\/product\/neomycin-monoclonal-antibody-adc-57244a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.abtriva.com\/ko\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/www.abtriva.com\/ko\/shop\/"},{"@type":"ListItem","position":3,"name":"Antibodies","item":"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/"},{"@type":"ListItem","position":4,"name":"Small Molecules Antibodies","item":"https:\/\/www.abtriva.com\/ko\/category\/antibodies\/small-molecules-antibodies\/"},{"@type":"ListItem","position":5,"name":"Neomycin Monoclonal Antibody"}]},{"@type":"WebSite","@id":"https:\/\/abtriva.com\/cn\/#website","url":"https:\/\/abtriva.com\/cn\/","name":"AbTrivia","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/abtriva.com\/cn\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ko_KR"}]}},"_links":{"self":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product\/88082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/comments?post=88082"}],"wp:attachment":[{"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/media?parent=88082"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_brand?post=88082"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_cat?post=88082"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.abtriva.com\/ko\/wp-json\/wp\/v2\/product_tag?post=88082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}